{"id":3174,"date":"2022-12-14T16:02:13","date_gmt":"2022-12-14T08:02:13","guid":{"rendered":"https:\/\/metalpie.com\/?post_type=product&#038;p=3174"},"modified":"2022-12-14T16:04:24","modified_gmt":"2022-12-14T08:04:24","slug":"%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8","status":"publish","type":"product","link":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/","title":{"rendered":"\u0410\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435 \u0434\u0435\u0442\u0430\u043b\u0438 \u0434\u043b\u044f \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u0435\u0439"},"content":{"rendered":"<div class=\"row large-columns-2 medium-columns- small-columns-\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_auto_body_parts.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_auto_body_parts.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3179,3180,3181\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_auto_body_parts.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_auto_body_parts-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_auto_body_parts-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_auto_body_parts-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_model_car_parts.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_model_car_parts.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3179,3180,3181\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_model_car_parts.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_model_car_parts-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_model_car_parts-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_model_car_parts-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_parts_made_of_aluminum.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_parts_made_of_aluminum.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3179,3180,3181\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_parts_made_of_aluminum.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_parts_made_of_aluminum-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_parts_made_of_aluminum-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_parts_made_of_aluminum-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3176,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"class_list":["post-3174","product","type-product","status-publish","has-post-thumbnail","product_cat-aluminum-vehicles","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum Cargo Trailers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/ru\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u0438\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u0437\u0430\u043f\u0447\u0430\u0441\u0442\u0438\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Cargo Trailers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/ru\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u0438\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u0437\u0430\u043f\u0447\u0430\u0441\u0442\u0438\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T08:04:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_parts.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/\",\"name\":\"Aluminum Cargo Trailers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_car_parts.webp\",\"datePublished\":\"2022-12-14T08:02:13+00:00\",\"dateModified\":\"2022-12-14T08:04:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_car_parts.webp\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_car_parts.webp\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/metalpie.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aluminum Car Parts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0410\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435 \u0433\u0440\u0443\u0437\u043e\u0432\u044b\u0435 \u043f\u0440\u0438\u0446\u0435\u043f\u044b","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/ru\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u0438\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u0437\u0430\u043f\u0447\u0430\u0441\u0442\u0438\/","og_locale":"ru_RU","og_type":"article","og_title":"Aluminum Cargo Trailers","og_url":"https:\/\/metalpie.com\/ru\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u0438\/\u0430\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435-\u0430\u0432\u0442\u043e\u0437\u0430\u043f\u0447\u0430\u0441\u0442\u0438\/","og_site_name":"METALPIE","article_modified_time":"2022-12-14T08:04:24+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_parts.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"1 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/","url":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/","name":"\u0410\u043b\u044e\u043c\u0438\u043d\u0438\u0435\u0432\u044b\u0435 \u0433\u0440\u0443\u0437\u043e\u0432\u044b\u0435 \u043f\u0440\u0438\u0446\u0435\u043f\u044b","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_parts.webp","datePublished":"2022-12-14T08:02:13+00:00","dateModified":"2022-12-14T08:04:24+00:00","breadcrumb":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_parts.webp","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_parts.webp","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%b7%d0%b0%d0%bf%d1%87%d0%b0%d1%81%d1%82%d0%b8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/metalpie.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aluminum Car Parts"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"\u041f\u0440\u0435\u0446\u0438\u0437\u0438\u043e\u043d\u043d\u043e\u0435 \u0438\u0437\u0433\u043e\u0442\u043e\u0432\u043b\u0435\u043d\u0438\u0435 \u043c\u0435\u0442\u0430\u043b\u043b\u0438\u0447\u0435\u0441\u043a\u0438\u0445 \u0438\u0437\u0434\u0435\u043b\u0438\u0439 | \u0418\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442\u044b, \u043f\u0440\u043e\u0446\u0435\u0441\u0441\u044b \u0438 \u043c\u043d\u043e\u0433\u043e\u0435 \u0434\u0440\u0443\u0433\u043e\u0435","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/product\/3174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/comments?post=3174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/media\/3176"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/media?parent=3174"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/product_brand?post=3174"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalpie.com\/ru\/wp-json\/wp\/v2\/product_cat?post=3174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}