{"id":3163,"date":"2022-12-14T15:21:27","date_gmt":"2022-12-14T07:21:27","guid":{"rendered":"https:\/\/metalpie.com\/?post_type=product&#038;p=3163"},"modified":"2022-12-14T16:06:11","modified_gmt":"2022-12-14T08:06:11","slug":"tanque-de-combustivel-de-aluminio-para-caminhoes","status":"publish","type":"product","link":"https:\/\/metalpie.com\/pt\/veiculos-de-aluminio\/tanque-de-combustivel-de-aluminio-para-caminhoes\/","title":{"rendered":"Tanque de combust\u00edvel de alum\u00ednio para caminh\u00e3o"},"content":{"rendered":"<div class=\"row large-columns-2 medium-columns- small-columns-\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_beds.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_beds.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3168,3169,3170,3171,3172,3173\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_beds.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_beds-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_beds-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_beds-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_left.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_left.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3168,3169,3170,3171,3172,3173\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_left.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_left-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_left-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_left-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_rack.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_rack.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3168,3169,3170,3171,3172,3173\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_rack.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_rack-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_rack-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel-tanks_for_truck_luggage_rack-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tank.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tank.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3168,3169,3170,3171,3172,3173\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tank.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tank-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tank-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tank-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_ladder.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_ladder.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3168,3169,3170,3171,3172,3173\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_ladder.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_ladder-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_ladder-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_ladder-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_sale.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_sale.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3168,3169,3170,3171,3172,3173\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_sale.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_sale-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_sale-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_fuel_tanks_sale-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3166,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"class_list":["post-3163","product","type-product","status-publish","has-post-thumbnail","product_cat-aluminum-vehicles","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum Cargo Trailers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/pt\/veiculos-de-aluminio\/tanque-de-combustivel-de-aluminio-para-caminhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Cargo Trailers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/pt\/veiculos-de-aluminio\/tanque-de-combustivel-de-aluminio-para-caminhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T08:06:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel_tanks_for_trucks.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/\",\"name\":\"Aluminum Cargo Trailers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_fuel_tanks_for_trucks.webp\",\"datePublished\":\"2022-12-14T07:21:27+00:00\",\"dateModified\":\"2022-12-14T08:06:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_fuel_tanks_for_trucks.webp\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_fuel_tanks_for_trucks.webp\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/metalpie.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aluminum Truck Fuel Tank\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reboques de carga de alum\u00ednio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/pt\/veiculos-de-aluminio\/tanque-de-combustivel-de-aluminio-para-caminhoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Aluminum Cargo Trailers","og_url":"https:\/\/metalpie.com\/pt\/veiculos-de-aluminio\/tanque-de-combustivel-de-aluminio-para-caminhoes\/","og_site_name":"METALPIE","article_modified_time":"2022-12-14T08:06:11+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel_tanks_for_trucks.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/","url":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/","name":"Reboques de carga de alum\u00ednio","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel_tanks_for_trucks.webp","datePublished":"2022-12-14T07:21:27+00:00","dateModified":"2022-12-14T08:06:11+00:00","breadcrumb":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel_tanks_for_trucks.webp","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_fuel_tanks_for_trucks.webp","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d1%82%d0%be%d0%bf%d0%bb%d0%b8%d0%b2%d0%bd%d1%8b%d0%b9-%d0%b1%d0%b0%d0%ba-%d0%b4%d0%bb%d1%8f-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/metalpie.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aluminum Truck Fuel Tank"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabrica\u00e7\u00e3o de metais de precis\u00e3o | Ferramentas, processos e muito mais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/product\/3163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/comments?post=3163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/media\/3166"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/media?parent=3163"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/product_brand?post=3163"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalpie.com\/pt\/wp-json\/wp\/v2\/product_cat?post=3163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}