{"id":3136,"date":"2022-12-14T15:00:14","date_gmt":"2022-12-14T07:00:14","guid":{"rendered":"https:\/\/metalpie.com\/?post_type=product&#038;p=3136"},"modified":"2022-12-14T15:04:44","modified_gmt":"2022-12-14T07:04:44","slug":"carrozzeria-in-alluminio","status":"publish","type":"product","link":"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/carrozzeria-in-alluminio\/","title":{"rendered":"Carrozzeria in alluminio"},"content":{"rendered":"<div class=\"row large-columns-2 medium-columns- small-columns-\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars_luggage_rack.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars_luggage_rack.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars_luggage_rack.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars_luggage_rack-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars_luggage_rack-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars_luggage_rack-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_car_pedals.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_car_pedals.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_car_pedals.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_car_pedals-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_car_pedals-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_car_pedals-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_cars_threshold_beam.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_cars_threshold_beam.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_cars_threshold_beam.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_cars_threshold_beam-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_cars_threshold_beam-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_body_cars_threshold_beam-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_body_battery_tray.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_body_battery_tray.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_body_battery_tray.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_body_battery_tray-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_body_battery_tray-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_car_body_battery_tray-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_front.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_front.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_front.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_front-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_front-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_front-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_left.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_left.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_left.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_left-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_left-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_left-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_right.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_right.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_right.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_right-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_right-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/Aluminum_car_frame_track_right-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_anti_collision_beam.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_anti_collision_beam.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_anti_collision_beam.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_anti_collision_beam-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_anti_collision_beam-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_anti_collision_beam-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_battery_tray.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_battery_tray.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_battery_tray.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_battery_tray-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_battery_tray-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_battery_tray-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3153,3154,3155,3156,3157,3158,3159,3160,3161,3162,3152\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bodied_cars-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3137,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"class_list":["post-3136","product","type-product","status-publish","has-post-thumbnail","product_cat-aluminum-vehicles","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum Cargo Trailers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/carrozzeria-in-alluminio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Cargo Trailers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/carrozzeria-in-alluminio\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T07:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_track.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/\",\"name\":\"Aluminum Cargo Trailers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/car_aluminum_body_track.jpg\",\"datePublished\":\"2022-12-14T07:00:14+00:00\",\"dateModified\":\"2022-12-14T07:04:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/car_aluminum_body_track.jpg\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/car_aluminum_body_track.jpg\",\"width\":1000,\"height\":750,\"caption\":\"aluminum car body track\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/metalpie.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aluminum Car Body\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rimorchi per il trasporto di merci in alluminio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/carrozzeria-in-alluminio\/","og_locale":"it_IT","og_type":"article","og_title":"Aluminum Cargo Trailers","og_url":"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/carrozzeria-in-alluminio\/","og_site_name":"METALPIE","article_modified_time":"2022-12-14T07:04:44+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_track.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/","url":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/","name":"Rimorchi per il trasporto di merci in alluminio","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_track.jpg","datePublished":"2022-12-14T07:00:14+00:00","dateModified":"2022-12-14T07:04:44+00:00","breadcrumb":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_track.jpg","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/car_aluminum_body_track.jpg","width":1000,"height":750,"caption":"aluminum car body track"},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/metalpie.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aluminum Car Body"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabbricazione di precisione del metallo - Strumenti, processi e altro ancora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product\/3136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/comments?post=3136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/media\/3137"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/media?parent=3136"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product_brand?post=3136"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product_cat?post=3136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}