{"id":3057,"date":"2022-12-13T09:51:55","date_gmt":"2022-12-13T01:51:55","guid":{"rendered":"https:\/\/metalpie.com\/?post_type=product&#038;p=3057"},"modified":"2022-12-14T10:43:22","modified_gmt":"2022-12-14T02:43:22","slug":"rimorchi-da-carico-in-alluminio","status":"publish","type":"product","link":"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/rimorchi-da-carico-in-alluminio\/","title":{"rendered":"Rimorchi per il trasporto di merci in alluminio"},"content":{"rendered":"<div class=\"row large-columns-1 medium-columns- small-columns-\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/all_aluminum_cargo_trailer.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/all_aluminum_cargo_trailer.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3059,3060,3061\" style=\"none\" columns=\"1\" image_size=\"original\" image_overlay=\"rgba(255, 255, 255, 0)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/all_aluminum_cargo_trailer.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/all_aluminum_cargo_trailer-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/all_aluminum_cargo_trailer-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/all_aluminum_cargo_trailer-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(255, 255, 255, 0)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/All_aluminum_enclosed_cargo_trailer.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/All_aluminum_enclosed_cargo_trailer.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3059,3060,3061\" style=\"none\" columns=\"1\" image_size=\"original\" image_overlay=\"rgba(255, 255, 255, 0)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/All_aluminum_enclosed_cargo_trailer.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/All_aluminum_enclosed_cargo_trailer-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/All_aluminum_enclosed_cargo_trailer-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/All_aluminum_enclosed_cargo_trailer-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(255, 255, 255, 0)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_cargo_trailer_for_sale.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_cargo_trailer_for_sale.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3059,3060,3061\" style=\"none\" columns=\"1\" image_size=\"original\" image_overlay=\"rgba(255, 255, 255, 0)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_cargo_trailer_for_sale.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_cargo_trailer_for_sale-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_cargo_trailer_for_sale-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_cargo_trailer_for_sale-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(255, 255, 255, 0)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3058,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"class_list":["post-3057","product","type-product","status-publish","has-post-thumbnail","product_cat-aluminum-vehicles","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum Cargo Trailers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/rimorchi-da-carico-in-alluminio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Cargo Trailers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/rimorchi-da-carico-in-alluminio\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T02:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/best_aluminum_cargo_trailer.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/\",\"name\":\"Aluminum Cargo Trailers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/best_aluminum_cargo_trailer.webp\",\"datePublished\":\"2022-12-13T01:51:55+00:00\",\"dateModified\":\"2022-12-14T02:43:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/best_aluminum_cargo_trailer.webp\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/best_aluminum_cargo_trailer.webp\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/metalpie.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aluminum Cargo Trailers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rimorchi per il trasporto di merci in alluminio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/rimorchi-da-carico-in-alluminio\/","og_locale":"it_IT","og_type":"article","og_title":"Aluminum Cargo Trailers","og_url":"https:\/\/metalpie.com\/it\/veicoli-in-alluminio\/rimorchi-da-carico-in-alluminio\/","og_site_name":"METALPIE","article_modified_time":"2022-12-14T02:43:22+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/best_aluminum_cargo_trailer.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/","url":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/","name":"Rimorchi per il trasporto di merci in alluminio","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/best_aluminum_cargo_trailer.webp","datePublished":"2022-12-13T01:51:55+00:00","dateModified":"2022-12-14T02:43:22+00:00","breadcrumb":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/best_aluminum_cargo_trailer.webp","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/best_aluminum_cargo_trailer.webp","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d1%8b%d0%b5-%d0%bf%d1%80%d0%b8%d1%86%d0%b5%d0%bf%d1%8b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/metalpie.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aluminum Cargo Trailers"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabbricazione di precisione del metallo - Strumenti, processi e altro ancora","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product\/3057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/comments?post=3057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/media\/3058"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/media?parent=3057"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product_brand?post=3057"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalpie.com\/it\/wp-json\/wp\/v2\/product_cat?post=3057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}