{"id":3277,"date":"2022-12-20T11:38:18","date_gmt":"2022-12-20T03:38:18","guid":{"rendered":"https:\/\/metalpie.com\/?post_type=product&#038;p=3277"},"modified":"2022-12-21T17:13:52","modified_gmt":"2022-12-21T09:13:52","slug":"caisse-de-camion-en-aluminium-pour-camion-leger","status":"publish","type":"product","link":"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-pour-camion-leger\/","title":{"rendered":"Caisse de camion en aluminium pour camion l\u00e9ger"},"content":{"rendered":"<div class=\"row large-columns-2 medium-columns- small-columns-\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_company_left_side.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_company_left_side.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_company_left_side.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_company_left_side-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_company_left_side-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_company_left_side-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_white_back_right.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_white_back_right.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_white_back_right.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_white_back_right-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_white_back_right-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_bed_truck_white_back_right-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_real_sence.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_real_sence.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_real_sence.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_real_sence-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_real_sence-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_real_sence-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_right_side.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_right_side.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_right_side.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_right_side-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_right_side-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_right_side-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_white_back.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_white_back.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_white_back.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_white_back-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_white_back-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_beds_for_trucks_white_back-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_back_right_side.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_back_right_side.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_back_right_side.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_back_right_side-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_back_right_side-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_back_right_side-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_white_left_side.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_white_left_side.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_white_left_side.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_white_left_side-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_white_left_side-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_flatbed_truck_bed_white_left_side-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_company_right_side.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_company_right_side.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_company_right_side.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_company_right_side-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_company_right_side-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_company_right_side-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_side_real_sence.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_side_real_sence.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_side_real_sence.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_side_real_sence-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_side_real_sence-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_side_real_sence-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_white_side_left.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_white_side_left.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_white_side_left.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_white_side_left-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_white_side_left-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_for_sale_white_side_left-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_left_side.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_left_side.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_left_side.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_left_side-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_left_side-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_left_side-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_red_side_right.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_red_side_right.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_red_side_right.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_red_side_right-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_red_side_right-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bed_red_side_right-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_company.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_company.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_company.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_company-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_company-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_company-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_red_side_left.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_red_side_left.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_red_side_left.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_red_side_left-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_red_side_left-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_red_side_left-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_white_left_back.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_white_left_back.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_white_left_back.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_white_left_back-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_white_left_back-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds_white_left_back-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed-.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed-.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed-.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed--300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed--768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed--800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_left_company.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_left_company.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_left_company.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_left_company-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_left_company-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_left_company-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_white_side_right.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_white_side_right.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_white_side_right.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_white_side_right-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_white_side_right-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/cargo_truck_bed_white_side_right-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/custom_aluminum_truck_beds_cutome.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/custom_aluminum_truck_beds_cutome.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/custom_aluminum_truck_beds_cutome.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/custom_aluminum_truck_beds_cutome-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/custom_aluminum_truck_beds_cutome-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/custom_aluminum_truck_beds_cutome-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_real_sence.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_real_sence.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_real_sence.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_real_sence-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_real_sence-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_real_sence-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_red_back.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_red_back.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_red_back.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_red_back-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_red_back-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_red_back-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_white_left_back.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_white_left_back.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3282,3283,3284,3285,3286,3287,3288,3289,3290,3291,3292,3293,3294,3295,3296,3297,3298,3299,3300,3301,3302,3303,3304,3305\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_white_left_back.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_white_left_back-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_white_left_back-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/truck_bed_aluminum_white_left_back-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3278,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"class_list":["post-3277","product","type-product","status-publish","has-post-thumbnail","product_cat-aluminum-vehicles","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum Truck Bed for Light Truck | Aluminum Truck Body<\/title>\n<meta name=\"description\" content=\"Hualv is the leading aluminum vehicle manufacturer, providing aluminum truck bodies and beds for many famous companies worldwide.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-pour-camion-leger\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Truck Bed for Light Truck | Aluminum Truck Body\" \/>\n<meta property=\"og:description\" content=\"Hualv is the leading aluminum vehicle manufacturer, providing aluminum truck bodies and beds for many famous companies worldwide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-pour-camion-leger\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T09:13:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/\",\"name\":\"Aluminum Truck Bed for Light Truck | Aluminum Truck Body\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_truck_beds.webp\",\"datePublished\":\"2022-12-20T03:38:18+00:00\",\"dateModified\":\"2022-12-21T09:13:52+00:00\",\"description\":\"Hualv is the leading aluminum vehicle manufacturer, providing aluminum truck bodies and beds for many famous companies worldwide.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_truck_beds.webp\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_truck_beds.webp\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/metalpie.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aluminum Truck Bed for Light Truck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caisse de camion en aluminium pour camion l\u00e9ger | Caisse de camion en aluminium","description":"Hualv est le principal fabricant de v\u00e9hicules en aluminium, fournissant des carrosseries de camions et des lits en aluminium \u00e0 de nombreuses entreprises de renom dans le monde entier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-pour-camion-leger\/","og_locale":"fr_FR","og_type":"article","og_title":"Aluminum Truck Bed for Light Truck | Aluminum Truck Body","og_description":"Hualv is the leading aluminum vehicle manufacturer, providing aluminum truck bodies and beds for many famous companies worldwide.","og_url":"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-pour-camion-leger\/","og_site_name":"METALPIE","article_modified_time":"2022-12-21T09:13:52+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/","url":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/","name":"Caisse de camion en aluminium pour camion l\u00e9ger | Caisse de camion en aluminium","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds.webp","datePublished":"2022-12-20T03:38:18+00:00","dateModified":"2022-12-21T09:13:52+00:00","description":"Hualv est le principal fabricant de v\u00e9hicules en aluminium, fournissant des carrosseries de camions et des lits en aluminium \u00e0 de nombreuses entreprises de renom dans le monde entier.","breadcrumb":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds.webp","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_beds.webp","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d0%b0%d1%8f-%d0%ba%d1%80%d0%be%d0%b2%d0%b0%d1%82%d1%8c-%d0%b4%d0%bb%d1%8f-%d0%bb%d0%b5%d0%b3%d0%ba%d0%be%d0%b3%d0%be-%d0%b3%d1%80%d1%83%d0%b7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/metalpie.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aluminum Truck Bed for Light Truck"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabrication de pr\u00e9cision des m\u00e9taux | Outils, processus et autres","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product\/3277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/comments?post=3277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media\/3278"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media?parent=3277"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3277"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}