{"id":3125,"date":"2022-12-14T13:41:46","date_gmt":"2022-12-14T05:41:46","guid":{"rendered":"https:\/\/metalpie.com\/?post_type=product&#038;p=3125"},"modified":"2022-12-14T13:46:00","modified_gmt":"2022-12-14T05:46:00","slug":"caisse-de-camion-en-aluminium-2","status":"publish","type":"product","link":"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-2\/","title":{"rendered":"Carrosserie de camion en aluminium"},"content":{"rendered":"<div class=\"row large-columns-2 medium-columns- small-columns-\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truc_body_brackev.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truc_body_brackev.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3130,3131,3132,3133,3134\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truc_body_brackev.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truc_body_brackev-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truc_body_brackev-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truc_body_brackev-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truck_body.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truck_body.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3130,3131,3132,3133,3134\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truck_body.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truck_body-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truck_body-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_box_truck_body-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_for_sale-1.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_for_sale-1.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3130,3131,3132,3133,3134\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_for_sale-1.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_for_sale-1-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_for_sale-1-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_for_sale-1-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers-1.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers-1.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3130,3131,3132,3133,3134\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers-1.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers-1-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers-1-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers-1-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers_bottom_plate.webp\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers_bottom_plate.webp\" class=\"attachment-original size-original\" alt=\"\" ids=\"3130,3131,3132,3133,3134\" style=\"none\" columns=\"2\" image_size=\"original\" image_overlay=\"rgba(0, 0, 0, 0.017)\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers_bottom_plate.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers_bottom_plate-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers_bottom_plate-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_manufacturers_bottom_plate-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                  <div class=\"overlay fill\"\n                      style=\"background-color: rgba(0, 0, 0, 0.017)\">\n                  <\/div>\n                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3126,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[98],"class_list":["post-3125","product","type-product","status-publish","has-post-thumbnail","product_cat-aluminum-vehicles","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aluminum Cargo Trailers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aluminum Cargo Trailers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-2\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T05:46:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_frame.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/\",\"name\":\"Aluminum Cargo Trailers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_truck_bodies_frame.png\",\"datePublished\":\"2022-12-14T05:41:46+00:00\",\"dateModified\":\"2022-12-14T05:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_truck_bodies_frame.png\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/aluminum_truck_bodies_frame.png\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/ru\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\\\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/metalpie.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aluminum Truck Body\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remorques cargo en aluminium","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Aluminum Cargo Trailers","og_url":"https:\/\/metalpie.com\/fr\/vehicules-en-aluminium\/caisse-de-camion-en-aluminium-2\/","og_site_name":"METALPIE","article_modified_time":"2022-12-14T05:46:00+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_frame.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/","url":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/","name":"Remorques cargo en aluminium","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_frame.png","datePublished":"2022-12-14T05:41:46+00:00","dateModified":"2022-12-14T05:46:00+00:00","breadcrumb":{"@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_frame.png","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/12\/aluminum_truck_bodies_frame.png","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/ru\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b5-%d0%b0%d0%b2%d1%82%d0%be%d0%bc%d0%be%d0%b1%d0%b8%d0%bb%d0%b8\/%d0%b0%d0%bb%d1%8e%d0%bc%d0%b8%d0%bd%d0%b8%d0%b5%d0%b2%d1%8b%d0%b9-%d0%ba%d1%83%d0%b7%d0%be%d0%b2-%d0%b3%d1%80%d1%83%d0%b7%d0%be%d0%b2%d0%b8%d0%ba%d0%b0-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/metalpie.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aluminum Truck Body"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabrication de pr\u00e9cision des m\u00e9taux | Outils, processus et autres","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product\/3125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/comments?post=3125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media\/3126"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media?parent=3125"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3125"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}