{"id":14864,"date":"2026-07-21T07:17:28","date_gmt":"2026-07-20T23:17:28","guid":{"rendered":"https:\/\/metalpie.com\/?p=14864"},"modified":"2026-07-21T07:18:40","modified_gmt":"2026-07-20T23:18:40","slug":"guide-des-modeles-de-moulage-metallique","status":"publish","type":"post","link":"https:\/\/metalpie.com\/fr\/blog\/guide-des-modeles-de-moulage-metallique\/","title":{"rendered":"Mod\u00e8les de moulage m\u00e9tallique : types, mat\u00e9riaux et guide de s\u00e9lection"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Qu'est-ce qu'un mod\u00e8le en fonderie ?<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Dans le secteur de la fonderie, un mod\u00e8le est une r\u00e9plique physique de l'objet final \u00e0 couler. Le mod\u00e8le de coul\u00e9e m\u00e9tallique d\u00e9finit la cavit\u00e9 du moule, dans laquelle le m\u00e9tal en fusion est coul\u00e9 pour obtenir la pi\u00e8ce souhait\u00e9e. Par cons\u00e9quent, la conception et la pr\u00e9cision du mod\u00e8le d\u00e9terminent directement la pr\u00e9cision, l'\u00e9tat de surface et la qualit\u00e9 de la pi\u00e8ce moul\u00e9e finale.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En r\u00e8gle g\u00e9n\u00e9rale, les moules utilis\u00e9s dans la fonderie sont class\u00e9s en deux cat\u00e9gories fondamentales en fonction de leur dur\u00e9e de vie :<\/p>\r\n\r\n\r\n\r\n<ol class=\"wp-block-list\">\r\n<li><strong>Mod\u00e8les r\u00e9utilisables :<\/strong> Couramment utilis\u00e9s dans le moulage au sable et le moulage au pl\u00e2tre. Ces mod\u00e8les permettent de r\u00e9aliser plusieurs moulages sans \u00eatre d\u00e9truits.<\/li>\r\n<li><strong>Mod\u00e8les de consommables (\u00e0 usage unique) :<\/strong> Utilis\u00e9 dans la fonderie de pr\u00e9cision (proc\u00e9d\u00e9 \u00e0 la cire perdue) ou la fonderie \u00e0 mousse perdue. Le mod\u00e8le est fondu, br\u00fbl\u00e9 ou vaporis\u00e9 avant ou pendant le processus de coul\u00e9e du m\u00e9tal.<\/li>\r\n<\/ol>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Les 12 types de mod\u00e8les utilis\u00e9s dans le moulage au sable en fonderie<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le choix du type de mod\u00e8le appropri\u00e9 d\u00e9pend du volume de production, de la taille de la pi\u00e8ce moul\u00e9e, de la complexit\u00e9 g\u00e9om\u00e9trique et de la m\u00e9thode de moulage. Voici les 12 types de mod\u00e8les de moulage m\u00e9tallique les plus courants utilis\u00e9s dans les fonderies modernes :<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-embed\">\r\n<div class=\"wp-block-embed__wrapper\">https:\/\/www.youtube.com\/watch?v=cBWavCXbKMo<\/div>\r\n<\/figure>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><em>1. Motif d'une seule pi\u00e8ce (unite)<\/em><\/li>\r\n<li><em>2. Patron en deux parties (s\u00e9par\u00e9)<\/em><\/li>\r\n<li><em>3. Patron en plusieurs pi\u00e8ces<\/em><\/li>\r\n<li><em>4. Motif de la plaque de correspondance<\/em><\/li>\r\n<li><em>5. Motif en grille<\/em><\/li>\r\n<li><em>6. Motif \u00ab squelette \u00bb<\/em><\/li>\r\n<li><em>7. Mod\u00e8le de balayage<\/em><\/li>\r\n<li><em>8. Patron de pi\u00e8ce d\u00e9tach\u00e9e<\/em><\/li>\r\n<li><em>9. Figure de man\u0153uvre \u00ab Cope and Drag \u00bb<\/em><\/li>\r\n<li><em>10. Motif \u00ab coquillage \u00bb<\/em><\/li>\r\n<li><em>11. Suivre le sch\u00e9ma de la planche<\/em><\/li>\r\n<li><em>12. Motif segmentaire<\/em><\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">1. Motif d'une seule pi\u00e8ce (unite)<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un mod\u00e8le monobloc ou massif est le type de mod\u00e8le de fonderie le plus simple et le moins co\u00fbteux. Fabriqu\u00e9 sans joints ni sections amovibles, il est g\u00e9n\u00e9ralement utilis\u00e9 pour les formes simples, la production en petites s\u00e9ries ou les pi\u00e8ces moul\u00e9es prototypes. Comme l'ensemble du mod\u00e8le repose dans un seul ch\u00e2ssis de moulage (g\u00e9n\u00e9ralement le ch\u00e2ssis de tirage), il n\u00e9cessite une surface de s\u00e9paration plane afin de faciliter son retrait sans endommager le sable.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">2. Patron en deux parties (s\u00e9par\u00e9)<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Lorsqu'une pi\u00e8ce moul\u00e9e pr\u00e9sente une g\u00e9om\u00e9trie complexe ou une ligne de joint irr\u00e9guli\u00e8re, on privil\u00e9gie un mod\u00e8le en deux parties (divis\u00e9). Le mod\u00e8le est divis\u00e9 horizontalement en deux moiti\u00e9s : la partie sup\u00e9rieure est plac\u00e9e dans le moule sup\u00e9rieur (cope), et la partie inf\u00e9rieure dans le moule inf\u00e9rieur (drag). Des goupilles de centrage sont int\u00e9gr\u00e9es aux surfaces de s\u00e9paration afin de garantir un alignement pr\u00e9cis entre les deux moiti\u00e9s.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">3. Patron en plusieurs pi\u00e8ces<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pour les pi\u00e8ces tr\u00e8s complexes qui ne peuvent pas \u00eatre d\u00e9moul\u00e9es \u00e0 l'aide d'un moule en deux parties, on utilise un moule en plusieurs parties. Celui-ci se compose de trois sections ou plus (par exemple, une partie sup\u00e9rieure, une partie centrale et une partie inf\u00e9rieure). Dans les configurations en trois parties, la section centrale est moul\u00e9e \u00e0 l'int\u00e9rieur d'un ch\u00e2ssis interm\u00e9diaire appel\u00e9 <em>bo\u00eete \u00e0 joues<\/em>.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">4. Motif de la plaque de correspondance<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Dans un moule \u00e0 plaques jumel\u00e9es, les demi-moules m\u00e2le et femelle sont mont\u00e9s de part et d'autre d'une plaque centrale en m\u00e9tal ou en bois. Les moules \u00e0 plaques jumel\u00e9es rationalisent le processus de moulage, r\u00e9duisent les besoins en main-d'\u0153uvre et offrent une pr\u00e9cision dimensionnelle sup\u00e9rieure. Ils sont largement utilis\u00e9s dans les fonderies automatis\u00e9es \u00e0 grand volume et pour le moulage de petites pi\u00e8ces en aluminium, en laiton ou en fonte.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">5. Motif en grille<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les mod\u00e8les \u00e0 canaux d'alimentation int\u00e8grent directement les pi\u00e8ces du mod\u00e8le au coulisseau et au syst\u00e8me d'alimentation. Gr\u00e2ce \u00e0 la formation automatique des canaux d'\u00e9coulement lors du moulage au sable, le m\u00e9tal en fusion s'\u00e9coule efficacement dans plusieurs cavit\u00e9s du moule en une seule coul\u00e9e. Bien que les co\u00fbts de fabrication initiaux soient plus \u00e9lev\u00e9s, les mod\u00e8les \u00e0 canaux d'alimentation augmentent consid\u00e9rablement le rendement et l'efficacit\u00e9 dans la production en s\u00e9rie.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">6. Motif \u00ab squelette \u00bb<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un mod\u00e8le \u00e0 ossature est un cadre en bois ou en m\u00e9tal, semblable \u00e0 des nervures, utilis\u00e9 pour des pi\u00e8ces moul\u00e9es exceptionnellement grandes et de forme simple (telles que de gros tuyaux, des vannes ou des socles de machines). Au lieu de construire un mod\u00e8le massif en bois, on tasse du sable ou de la terre glaise \u00e0 l'int\u00e9rieur et on le lisse \u00e0 la main le long de l'ossature. Cette conception permet de r\u00e9duire les co\u00fbts de mat\u00e9riaux et d'all\u00e9ger consid\u00e9rablement le poids du mod\u00e8le.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">7. Mod\u00e8le de balayage<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un moule \u00e0 balayage est constitu\u00e9 d\u2019une planche en bois fa\u00e7onn\u00e9e selon le profil souhait\u00e9, qui tourne autour d\u2019un axe vertical central. En balayant le sable compact\u00e9, la planche forme une cavit\u00e9 de moulage \u00e0 sym\u00e9trie de r\u00e9volution (comme pour les grandes cloches, les cylindres ou les bassins circulaires). Cela \u00e9vite d\u2019avoir recours \u00e0 des mod\u00e8les massifs co\u00fbteux et \u00e0 taille r\u00e9elle pour les grandes pi\u00e8ces sym\u00e9triques.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">8. Patron de pi\u00e8ce d\u00e9tach\u00e9e<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les mod\u00e8les \u00e0 pi\u00e8ces amovibles sont con\u00e7us pour les pi\u00e8ces moul\u00e9es pr\u00e9sentant des surplombs, des saillies ou des contre-d\u00e9pouilles situ\u00e9s au-dessus ou en dessous de la ligne de joint principale. Les parties saillantes sont fix\u00e9es de mani\u00e8re amovible au corps principal \u00e0 l'aide de goupilles. Une fois le mod\u00e8le principal extrait du sable, les pi\u00e8ces amovibles sont r\u00e9cup\u00e9r\u00e9es s\u00e9par\u00e9ment, ce qui \u00e9vite l'effondrement de la paroi du moule.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">9. Figure de man\u0153uvre \u00ab Cope and Drag \u00bb<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">\u00c0 l'instar des moules \u00e0 division, les moules \u00ab cope \u00bb et \u00ab drag \u00bb se composent de deux parties distinctes mont\u00e9es sur des plaques de moulage individuelles. Les moules \u00ab cope \u00bb et \u00ab drag \u00bb peuvent \u00eatre fabriqu\u00e9s simultan\u00e9ment sur des machines de moulage distinctes par des \u00e9quipes ind\u00e9pendantes. Cette m\u00e9thode est indispensable pour les pi\u00e8ces moul\u00e9es industrielles lourdes ou produites en grande s\u00e9rie.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">10. Motif \u00ab coquillage \u00bb<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les mod\u00e8les de coques sont des mod\u00e8les m\u00e9talliques sp\u00e9cialis\u00e9s, principalement utilis\u00e9s pour les proc\u00e9d\u00e9s de moulage en coquille ou pour la fabrication de structures creuses \u00e0 parois minces. Les deux moiti\u00e9s du mod\u00e8le sont fix\u00e9es sur des supports, chauff\u00e9es, puis recouvertes de sable li\u00e9 \u00e0 la r\u00e9sine afin de former un moule en coquille de sable lisse et de haute pr\u00e9cision.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">11. Suivre le sch\u00e9ma de la planche<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Une planche de soutien n'est pas un moule en soi, mais une planche de bois aux contours sur mesure utilis\u00e9e pour soutenir les moules structurellement fragiles ou \u00e0 parois minces pendant le bourrage. Elle emp\u00eache les parties d\u00e9licates du moule de se plier, de se casser ou de se d\u00e9former sous la pression m\u00e9canique exerc\u00e9e par le bourrage de sable.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">12. Motif segmentaire<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un motif segment\u00e9 fonctionne selon un principe similaire \u00e0 celui d'un motif de balayage, mais au lieu d'une rotation compl\u00e8te \u00e0 360 degr\u00e9s, il utilise une section (un segment) du profil. Le segment est tourn\u00e9 pas \u00e0 pas autour d'un axe central afin de r\u00e9aliser des structures circulaires ou en forme d'anneau (telles que des \u00e9bauches d'engrenages et de grandes brides).<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Mat\u00e9riaux couramment utilis\u00e9s pour les mod\u00e8les de moulage m\u00e9tallique<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le choix d'un mat\u00e9riau appropri\u00e9 pour le mod\u00e8le est essentiel pour trouver le juste \u00e9quilibre entre la dur\u00e9e de vie du mod\u00e8le, son co\u00fbt et les tol\u00e9rances dimensionnelles :<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><strong>Bois (teck, acajou, pin) :<\/strong> Peu co\u00fbteux, facile \u00e0 usiner, l\u00e9ger ; id\u00e9al pour les pi\u00e8ces moul\u00e9es en petites s\u00e9ries ou les prototypes.<\/li>\r\n<li><strong>M\u00e9taux (aluminium, fonte, laiton) :<\/strong> Haute r\u00e9sistance m\u00e9canique, r\u00e9sistance exceptionnelle \u00e0 l'usure, grande stabilit\u00e9 dimensionnelle ; privil\u00e9gi\u00e9 pour les s\u00e9ries de production de longue dur\u00e9e.<\/li>\r\n<li><strong>Plastiques et r\u00e9sines (\u00e9poxy, polyur\u00e9thane) :<\/strong> R\u00e9sistant \u00e0 la corrosion, l\u00e9ger, finition de surface lisse ; excellente alternative aux mod\u00e8les m\u00e9talliques.<\/li>\r\n<li><strong>Mod\u00e8les imprim\u00e9s en 3D (PLA, ABS, r\u00e9sine) :<\/strong> D\u00e9lais d'ex\u00e9cution courts pour le prototypage rapide et les g\u00e9om\u00e9tries personnalis\u00e9es tr\u00e8s complexes.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Tol\u00e9rances critiques des motifs dans la conception des pi\u00e8ces moul\u00e9es<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Un mod\u00e8le n'a jamais exactement les m\u00eames dimensions que la pi\u00e8ce moul\u00e9e finale. Les ing\u00e9nieurs de fonderie pr\u00e9voient des tol\u00e9rances sp\u00e9cifiques lors de la fabrication du mod\u00e8le afin de tenir compte du comportement du m\u00e9tal et des processus de finition :<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><strong>Marge de retrait :<\/strong> Tient compte de la contraction volum\u00e9trique qui se produit lorsque le m\u00e9tal en fusion refroidit et se solidifie.<\/li>\r\n<li><strong>Tol\u00e9rance de conicit\u00e9 :<\/strong> Ajoute un l\u00e9ger biseau aux parois verticales afin de permettre un d\u00e9moulage en douceur sans endommager les parois du moule.<\/li>\r\n<li><strong>Tol\u00e9rance d'usinage (finition) :<\/strong> Permet d'augmenter l'\u00e9paisseur de la pi\u00e8ce sur les surfaces destin\u00e9es \u00e0 un usinage CNC ou \u00e0 un meulage apr\u00e8s coul\u00e9e.<\/li>\r\n<li><strong>Tol\u00e9rance de distorsion :<\/strong> Pr\u00e9voit des contraintes de refroidissement in\u00e9gales dans les sections minces ou asym\u00e9triques.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Guide de s\u00e9lection des patrons : comment choisir celui qui convient \u00e0 votre projet<\/h2>\r\n\r\n\r\n\r\n<figure class=\"wp-block-table\">\r\n<table>\r\n<thead>\r\n<tr>\r\n<th>Exigences relatives au casting<\/th>\r\n<th>Type de motif recommand\u00e9<\/th>\r\n<th>Le meilleur tissu pour les patrons<\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr>\r\n<td>Prototypage \/ Pi\u00e8ce unique<\/td>\r\n<td>Pi\u00e8ce unique \/ Motif en balayage<\/td>\r\n<td>Bois \/ Impression 3D<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Petit lot (forme complexe)<\/td>\r\n<td>Pi\u00e8ce d\u00e9tach\u00e9e \/ Motif divis\u00e9<\/td>\r\n<td>Bois \/ R\u00e9sine synth\u00e9tique<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Grand volume (moulage au sable automatis\u00e9)<\/td>\r\n<td>Plaque de correspondance \/ Gabarit de forme et de contre-forme<\/td>\r\n<td>Aluminium \/ Fonte<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Grandes structures sym\u00e9triques \/ en anneau<\/td>\r\n<td>Balayage \/ Motif segment\u00e9<\/td>\r\n<td>Cadre en bois \/ Aluminium<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/figure>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le choix du mod\u00e8le de moulage m\u00e9tallique optimal a une incidence directe sur l'investissement en outillage, la cadence de production et la pr\u00e9cision des pi\u00e8ces. En adaptant votre volume de production et la g\u00e9om\u00e9trie de vos pi\u00e8ces \u00e0 une conception de mod\u00e8le et \u00e0 un mat\u00e9riau appropri\u00e9s, les fonderies peuvent r\u00e9duire au minimum les d\u00e9fauts et diminuer les co\u00fbts de fabrication. Si vous d\u00e9veloppez un composant m\u00e9tallique sur mesure, n'h\u00e9sitez pas \u00e0 consulter notre \u00e9quipe d'ing\u00e9nieurs chez METALPIE afin d'optimiser vos conceptions de moulage et votre strat\u00e9gie en mati\u00e8re de mod\u00e8les.<\/p>","protected":false},"excerpt":{"rendered":"<p>Qu'est-ce qu'un mod\u00e8le en fonderie ? Dans le secteur de la fonderie, un mod\u00e8le est une r\u00e9plique physique de l'objet final \u00e0 couler. Le mod\u00e8le de fonderie d\u00e9finit la cavit\u00e9 du moule, dans laquelle le m\u00e9tal en fusion est coul\u00e9 pour cr\u00e9er la pi\u00e8ce souhait\u00e9e. Par cons\u00e9quent, la conception et la pr\u00e9cision du mod\u00e8le d\u00e9terminent directement la pr\u00e9cision, l'\u00e9tat de surface et\u2026<\/p>","protected":false},"author":11,"featured_media":13835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Metal Casting Patterns: Types, Materials, and Selection Guide - METALPIE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/fr\/blog\/guide-des-modeles-de-moulage-metallique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metal Casting Patterns: Types, Materials, and Selection Guide - METALPIE\" \/>\n<meta property=\"og:description\" content=\"What is a Pattern in Metal Casting? In the foundry industry, a pattern is a physical replica of the final object to be cast. The metal casting pattern shapes the mold cavity, into which molten metal is poured to create the desired part. Therefore, pattern design and accuracy directly dictate the precision, surface finish, and...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/fr\/blog\/guide-des-modeles-de-moulage-metallique\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-20T23:17:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T23:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/01\/12-types-of-patterns-in-casting-process.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"DC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/\"},\"author\":{\"name\":\"DC\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#\\\/schema\\\/person\\\/d344990177b678113288be4309906d71\"},\"headline\":\"Metal Casting Patterns: Types, Materials, and Selection Guide\",\"datePublished\":\"2026-07-20T23:17:28+00:00\",\"dateModified\":\"2026-07-20T23:18:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/\"},\"wordCount\":1148,\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/12-types-of-patterns-in-casting-process.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/\",\"url\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/\",\"name\":\"Metal Casting Patterns: Types, Materials, and Selection Guide - METALPIE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/12-types-of-patterns-in-casting-process.jpg\",\"datePublished\":\"2026-07-20T23:17:28+00:00\",\"dateModified\":\"2026-07-20T23:18:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/#\\\/schema\\\/person\\\/d344990177b678113288be4309906d71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#primaryimage\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/12-types-of-patterns-in-casting-process.jpg\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/12-types-of-patterns-in-casting-process.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/metal-casting-patterns-guide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metalpie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/metalpie.com\\\/blog\\\/category\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Metal Casting Patterns: Types, Materials, and Selection Guide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#website\",\"url\":\"https:\\\/\\\/metalpie.com\\\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metalpie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/#\\\/schema\\\/person\\\/d344990177b678113288be4309906d71\",\"name\":\"DC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/litespeed\\\/avatar\\\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1788153009\",\"url\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/litespeed\\\/avatar\\\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1788153009\",\"contentUrl\":\"https:\\\/\\\/metalpie.com\\\/wp-content\\\/litespeed\\\/avatar\\\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1788153009\",\"caption\":\"DC\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mod\u00e8les de moulage des m\u00e9taux : types, mat\u00e9riaux et guide de s\u00e9lection - METALPIE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/fr\/blog\/guide-des-modeles-de-moulage-metallique\/","og_locale":"fr_FR","og_type":"article","og_title":"Metal Casting Patterns: Types, Materials, and Selection Guide - METALPIE","og_description":"What is a Pattern in Metal Casting? In the foundry industry, a pattern is a physical replica of the final object to be cast. The metal casting pattern shapes the mold cavity, into which molten metal is poured to create the desired part. Therefore, pattern design and accuracy directly dictate the precision, surface finish, and...","og_url":"https:\/\/metalpie.com\/fr\/blog\/guide-des-modeles-de-moulage-metallique\/","og_site_name":"METALPIE","article_published_time":"2026-07-20T23:17:28+00:00","article_modified_time":"2026-07-20T23:18:40+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/01\/12-types-of-patterns-in-casting-process.jpg","type":"image\/jpeg"}],"author":"DC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"DC","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#article","isPartOf":{"@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/"},"author":{"name":"DC","@id":"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71"},"headline":"Metal Casting Patterns: Types, Materials, and Selection Guide","datePublished":"2026-07-20T23:17:28+00:00","dateModified":"2026-07-20T23:18:40+00:00","mainEntityOfPage":{"@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/"},"wordCount":1148,"image":{"@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/01\/12-types-of-patterns-in-casting-process.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/","url":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/","name":"Mod\u00e8les de moulage des m\u00e9taux : types, mat\u00e9riaux et guide de s\u00e9lection - METALPIE","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#primaryimage"},"image":{"@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/01\/12-types-of-patterns-in-casting-process.jpg","datePublished":"2026-07-20T23:17:28+00:00","dateModified":"2026-07-20T23:18:40+00:00","author":{"@id":"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71"},"breadcrumb":{"@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#primaryimage","url":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/01\/12-types-of-patterns-in-casting-process.jpg","contentUrl":"https:\/\/metalpie.com\/wp-content\/uploads\/2022\/01\/12-types-of-patterns-in-casting-process.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/blog\/metal-casting-patterns-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/metalpie.com\/blog\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"Metal Casting Patterns: Types, Materials, and Selection Guide"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabrication de pr\u00e9cision des m\u00e9taux | Outils, processus et autres","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71","name":"DC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1788153009","url":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1788153009","contentUrl":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1788153009","caption":"DC"}}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts\/14864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/comments?post=14864"}],"version-history":[{"count":2,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts\/14864\/revisions"}],"predecessor-version":[{"id":14866,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts\/14864\/revisions\/14866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media\/13835"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media?parent=14864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/categories?post=14864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/tags?post=14864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}