{"id":14735,"date":"2021-10-08T15:30:27","date_gmt":"2021-10-08T07:30:27","guid":{"rendered":"https:\/\/metalpie.com\/?p=14735"},"modified":"2025-10-07T00:18:53","modified_gmt":"2025-10-06T16:18:53","slug":"methodes-dexploitation-souterraine","status":"publish","type":"post","link":"https:\/\/metalpie.com\/fr\/blog\/methodes-dexploitation-souterraine\/","title":{"rendered":"M\u00e9thodes d'exploitation souterraine"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Instruction<\/h2>\n<p>Il y a beaucoup de sujets et de conversations sur les m\u00e9thodes d'exploitation mini\u00e8re souterraine, mais il n'y a toujours pas de r\u00e9ponse. L'un des principaux sujets est l'exploitation mini\u00e8re souterraine. Si vous souhaitez rechercher des articles sur les m\u00e9thodes d'exploitation mini\u00e8re souterraine, vous \u00eates au bon endroit. Cet article vous pr\u00e9sentera les m\u00e9thodes d'exploitation mini\u00e8re souterraine sous diff\u00e9rents aspects.<\/p>\n<h2 class=\"wp-block-heading\">Qu'est-ce que l'exploitation mini\u00e8re souterraine ?<\/h2>\n<p>Avant de comprendre ce qu'est l'exploitation mini\u00e8re, il est tr\u00e8s important de comprendre ce qu'est l'exploitation mini\u00e8re souterraine ou la d\u00e9finition de l'exploitation mini\u00e8re souterraine. L'exploitation mini\u00e8re souterraine est un processus qui implique l'extraction d'un m\u00e9tal ou d'un combustible fossile du sol. Il s'agit de la m\u00e9thode d'exploitation mini\u00e8re la plus efficace et la plus connue. Le processus d'exploitation mini\u00e8re souterraine est utile pour l'extraction de l'or, de l'argent, du plomb et m\u00eame des pierres pr\u00e9cieuses. Il est \u00e9galement tr\u00e8s utile pour l'extraction du charbon, du sel et des sables bitumineux.<\/p>\n<h2 class=\"wp-block-heading\">M\u00e9thodes d'exploitation souterraine<\/h2>\n<p>Il existe cinq m\u00e9thodes d'exploitation mini\u00e8re souterraine, que vous devez comprendre lorsque vous cherchez \u00e0 en savoir plus.<\/p>\n<h3 class=\"wp-block-heading\">Exploitation mini\u00e8re \u00e0 ciel ouvert<\/h3>\n<p>Le premier type d'exploitation mini\u00e8re souterraine est l'exploitation \u00e0 ciel ouvert. L'exploitation \u00e0 ciel ouvert est un processus qui consiste \u00e0 extraire les min\u00e9raux. Pour ce faire, il faut enlever le sol et la roche. Cette m\u00e9thode d'exploitation souterraine est l'enl\u00e8vement des morts-terrains. La plupart du temps, elle est utilis\u00e9e pour l'extraction du charbon et du lignite. Il existe deux types d'exploitation \u00e0 ciel ouvert : l'exploitation par zone et l'exploitation en courbes de niveau. L'extraction par zone est utilis\u00e9e dans cette m\u00e9thode d'extraction souterraine, qui a \u00e9t\u00e9 d\u00e9pos\u00e9e sur une plus grande surface. L'exploitation en courbes de niveau est pratiqu\u00e9e dans les r\u00e9gions vallonn\u00e9es et, dans ce cas, le minerai se d\u00e9pose sur le sol.<\/p>\n<h3 class=\"wp-block-heading\">Exploitation \u00e0 ciel ouvert<\/h3>\n<p>La deuxi\u00e8me m\u00e9thode d'exploitation souterraine est l'exploitation \u00e0 ciel ouvert. Le processus d'exploitation \u00e0 ciel ouvert est utilis\u00e9 pour l'extraction de roches et m\u00eame de min\u00e9raux. Il s'agit de l'un des meilleurs types d'exploitation souterraine, con\u00e7u pour les personnes qui cherchent \u00e0 extraire des min\u00e9raux. Il s'agit d'un proc\u00e9d\u00e9 d'extraction \u00e0 ciel ouvert, mais ces deux m\u00e9thodes fonctionnent diff\u00e9remment.<\/p>\n<h3 class=\"wp-block-heading\">Enl\u00e8vement de la cime des montagnes<\/h3>\n<p>La troisi\u00e8me m\u00e9thode d'exploitation souterraine est l'extraction par le sommet des montagnes. Comme son nom l'indique, cette m\u00e9thode d'exploitation mini\u00e8re souterraine est utilis\u00e9e dans les montagnes. Elle consiste \u00e0 enlever le sommet de la montagne qui la recouvre. Dans cette m\u00e9thode, des explosifs sont utilis\u00e9s pour briser les couches de roche et pour enlever le sommet de la veine de charbon. Ce proc\u00e9d\u00e9 d'extraction souterraine est utilis\u00e9 pour extraire le charbon, qui est pr\u00e9sent en profondeur sur une distance de 400 pieds de la terre.<\/p>\n<h3 class=\"wp-block-heading\">Dragage<\/h3>\n<p>Le dragage est l'autre m\u00e9thode d'extraction souterraine pour extraire l'or. Dans cette m\u00e9thode, de petites dragues effectuent tous les processus d'extraction souterraine. Tout cela se fait \u00e0 l'aide d'un convoyeur \u00e0 bande. Les activit\u00e9s de creusement authentiques de grande envergure utilisent r\u00e9guli\u00e8rement une drague \u00e0 roue libre ; un bateau ressemblant \u00e0 un canal qui ramasse les mat\u00e9riaux par le biais d'une ligne de transport \u00e0 l'avant, tamise la partie id\u00e9ale et renvoie les mat\u00e9riaux ind\u00e9sirables \u00e0 l'eau par le biais d'une autre ligne de transport \u00e0 l'arri\u00e8re. Dans les vall\u00e9es rocheuses avec des nappes phr\u00e9atiques peu profondes, un excavateur glissant peut g\u00e9rer les r\u00e9sidus libres gr\u00e2ce \u00e0 son effort.<\/p>\n<h3 class=\"wp-block-heading\">Exploitation mini\u00e8re des hauts murs<\/h3>\n<p>La derni\u00e8re m\u00e9thode d'exploitation souterraine est l'exploitation en hauteur. Le processus d'exploitation mini\u00e8re souterraine en hauteur consiste \u00e0 effectuer l'exploitation mini\u00e8re dans les zones adjacentes au charbon. Il est tr\u00e8s utile pour r\u00e9cup\u00e9rer tous les morts-terrains de la veine de charbon. D'apr\u00e8s ce qui pr\u00e9c\u00e8de, nous pensons que vous avez compris la d\u00e9finition de l'exploitation mini\u00e8re souterraine et certaines m\u00e9thodes d'exploitation mini\u00e8re souterraine. Il est maintenant temps de comprendre les impacts environnementaux de l'exploitation souterraine, ainsi que ses avantages et ses inconv\u00e9nients.<strong>.\u00a0<\/strong>Si vous \u00eates soucieux de l'environnement, vous devriez craquer pour les informations ci-dessous :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14738 size-full\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery.webp\" alt=\"\" width=\"1956\" height=\"1216\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery.webp 1956w, https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery-300x187.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery-1030x640.webp 1030w, https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery-768x477.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery-1536x955.webp 1536w, https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery-18x12.webp 18w, https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery-800x497.webp 800w\" sizes=\"auto, (max-width: 1956px) 100vw, 1956px\" \/><\/p>\n<h2 class=\"wp-block-heading\">Avantages de l'exploitation mini\u00e8re souterraine<\/h2>\n<ul class=\"wp-block-list\">\n<li>Il s'agit de la meilleure m\u00e9thode d'exploitation souterraine, qui permet d'extraire les ressources naturelles de la terre.<\/li>\n<li>Il s'agit d'un processus qui pr\u00e9sente des avantages \u00e9conomiques et financiers consid\u00e9rables.<\/li>\n<li>Compar\u00e9 aux autres proc\u00e9d\u00e9s d'extraction souterraine, ce proc\u00e9d\u00e9 est le plus s\u00fbr.<\/li>\n<li>C'est le seul proc\u00e9d\u00e9 qui soit la meilleure option pour travailler sur de plus grandes surfaces.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\">Inconv\u00e9nients<\/h2>\n<p>Apr\u00e8s avoir compris les avantages, il faut maintenant conna\u00eetre les inconv\u00e9nients de l'exploitation mini\u00e8re souterraine. Le processus d'exploitation mini\u00e8re souterraine est dangereux pour l'environnement et entra\u00eene des effets \u00e0 long terme.<\/p>\n<h3 class=\"wp-block-heading\">Impact de l'exploitation du sous-sol sur l'environnement<\/h3>\n<p>Les impacts environnementaux de l'exploitation mini\u00e8re souterraine sont consid\u00e9rables. Il y a quelques ann\u00e9es, les habitants des Appalaches ont d\u00e9couvert que des milliers de kilom\u00e8tres avaient \u00e9t\u00e9 laiss\u00e9s en friche apr\u00e8s le processus d'exploitation mini\u00e8re \u00e0 ciel ouvert. M\u00eame si, apr\u00e8s quelques ann\u00e9es, les terres exploit\u00e9es en subsurface ont subi des glissements de terrain, des inondations, des mines de montagne et d'autres changements. De plus, les chutes d'eau ont \u00e9galement connu des probl\u00e8mes de drainage, d'\u00e9rosion, de pollution de l'eau et d'autres changements majeurs.<\/p>\n<h3 class=\"wp-block-heading\">Cause des dommages aux ressources fonci\u00e8res<\/h3>\n<p>Si l'on examine l'impact \u00e0 long terme de l'exploitation mini\u00e8re souterraine, on s'aper\u00e7oit qu'elle cause des dommages aux ressources du sol. L'exploitation \u00e0 ciel ouvert a un impact sur la qualit\u00e9 du sol, qui est tr\u00e8s importante pour la croissance et le d\u00e9veloppement des cultures. Elle a un impact sur les micro-organismes pr\u00e9sents dans le sol, ce qui le rend plus fertile. En outre, il existe de nombreux exemples d'exploitation mini\u00e8re souterraine, qui ont de nombreux effets n\u00e9fastes sur l'atmosph\u00e8re. Le processus d'exploitation mini\u00e8re souterraine a \u00e9galement un impact sur la croissance des plantes et autres l\u00e9gumes. Il alt\u00e8re \u00e9galement la puissance du sol.<\/p>\n<h3 class=\"wp-block-heading\">Impact sur la qualit\u00e9 de l'eau<\/h3>\n<p>L'eau est tr\u00e8s importante pour notre vie, mais apr\u00e8s l'exploitation mini\u00e8re souterraine, sa qualit\u00e9 est alt\u00e9r\u00e9e. Tout cela pollue les r\u00e9serves d'eau et les cours d'eau. L'eau prend une couleur rouge ou orange, et il est m\u00eame tr\u00e8s difficile de v\u00e9rifier que l'eau est affect\u00e9e. N\u00e9anmoins, les diff\u00e9rents types de contamination sont plus facilement identifiables. Un cours d'eau exceptionnellement acide peut sembler tout \u00e0 fait comparable \u00e0 un cours d'eau parfait, sauf si l'on constate qu'il ne contient pas de poissons.<\/p>\n<h3 class=\"wp-block-heading\">D\u00e9g\u00e2ts caus\u00e9s par la faune<\/h3>\n<p>La vie sauvage est souvent gravement menac\u00e9e par l'exploitation mini\u00e8re \u00e0 ciel ouvert. Pour l'instant, toutes les esp\u00e8ces sont soit an\u00e9anties, soit d\u00e9racin\u00e9es de l'espace de la mine. L'exploitation mini\u00e8re peut \u00e9galement avoir des effets antagonistes \u00e0 long terme sur la vie naturelle, notamment en entravant son territoire ou son climat local. De nombreuses esp\u00e8ces animales ne peuvent pas s'acclimater aux changements provoqu\u00e9s par l'influence d\u00e9stabilisante de l'exploitation mini\u00e8re. Dans les situations o\u00f9 un espace de vie important (comme un lieu favorable essentiel) est an\u00e9anti, l'esp\u00e8ce risque de dispara\u00eetre. Les milieux exceptionnels comme les falaises, les cavernes et les for\u00eats anciennes peuvent \u00eatre difficiles \u00e0 restaurer. Les grandes mines, comme celles de l'Ouest, peuvent perturber les voies de migration et les zones d'hivernage de base des grands gibiers.<\/p>\n<h2 class=\"wp-block-heading\">Exemples d'exploitation mini\u00e8re souterraine<\/h2>\n<p>Il n'est pas rare d'utiliser des m\u00e9thodes d'exploitation mini\u00e8re souterraine. Voici deux exemples d'exploitation mini\u00e8re avec des m\u00e9thodes d'exploitation souterraine. La mine d'or de Zhangjiakou : Apr\u00e8s des ann\u00e9es d'exploration, la mine d'or de Zhangjiakou a appliqu\u00e9 et test\u00e9 avec succ\u00e8s la m\u00e9thode d'exploitation souterraine. Les joints se d\u00e9veloppent tr\u00e8s bien.<\/p>\n<p>La forme du corps min\u00e9ralis\u00e9 est complexe, et l'\u00e9paisseur et l'angle d'inclinaison varient consid\u00e9rablement. Lors de l'exploitation de corps min\u00e9ralis\u00e9s minces l\u00e9g\u00e8rement inclin\u00e9s avec des toits instables, on adopte d'abord la m\u00e9thode de sp\u00e9l\u00e9ologie, qui n'est pas efficace, puis on utilise diverses formes de m\u00e9thodes d'exploitation souterraine d'acc\u00e8s pour obtenir de meilleurs r\u00e9sultats.<\/p>\n<p>Mine d'or de Xiangxi : Lors de l'exploitation de filons de maille, la m\u00e9thode d'exploitation souterraine a \u00e9t\u00e9 utilis\u00e9e \u00e0 l'origine pour couper les parois et les remplir. Le corps du minerai \u00e9tant \u00e9pais, il est difficile de trouver des mat\u00e9riaux de remplissage, la s\u00e9curit\u00e9 est m\u00e9diocre, l'intensit\u00e9 du travail des ouvriers est \u00e9lev\u00e9e et la productivit\u00e9 est faible. Am\u00e9liorer la capacit\u00e9 de production des blocs de minerai et r\u00e9duire les co\u00fbts d'exploitation.<\/p>\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n<p>Ce qui pr\u00e9c\u00e8de vous a pr\u00e9sent\u00e9 les types d'exploitation mini\u00e8re souterraine, la d\u00e9finition de l'exploitation mini\u00e8re souterraine, les impacts environnementaux de l'exploitation mini\u00e8re souterraine et des exemples d'exploitation mini\u00e8re souterraine. Si vous souhaitez toujours comprendre l'exploitation mini\u00e8re de surface et l'exploitation mini\u00e8re souterraine, nous esp\u00e9rons que vous avez enfin tout compris sur les m\u00e9thodes d'exploitation mini\u00e8re souterraine.<\/p>","protected":false},"excerpt":{"rendered":"<p>Instruction Il y a beaucoup de sujets et de conversations sur les m\u00e9thodes d'exploitation mini\u00e8re souterraine, mais il n'y a toujours pas de r\u00e9ponse. L'un des principaux sujets est l'exploitation mini\u00e8re souterraine. Si vous souhaitez rechercher des articles sur les m\u00e9thodes d'exploitation mini\u00e8re souterraine, vous \u00eates au bon endroit. Cet article vous pr\u00e9sentera les m\u00e9thodes d'exploitation mini\u00e8re souterraine sous diff\u00e9rents aspects....<\/p>","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14735","post","type-post","status-publish","format-standard","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Subsurface Mining Methods<\/title>\n<meta name=\"description\" content=\"Subsurface mining is a process that involves the extraction of a metal or fossil fuel from the ground. It is the most well-known mining method.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/fr\/blog\/methodes-dexploitation-souterraine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subsurface Mining Methods\" \/>\n<meta property=\"og:description\" content=\"Subsurface mining is a process that involves the extraction of a metal or fossil fuel from the ground. It is the most well-known mining method.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/fr\/blog\/methodes-dexploitation-souterraine\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-08T07:30:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T16:18:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery.webp\" \/>\n<meta name=\"author\" content=\"DC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"DC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/\",\"url\":\"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/\",\"name\":\"Subsurface Mining Methods\",\"isPartOf\":{\"@id\":\"https:\/\/metalpie.com\/#website\"},\"datePublished\":\"2021-10-08T07:30:27+00:00\",\"dateModified\":\"2025-10-06T16:18:53+00:00\",\"author\":{\"@id\":\"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71\"},\"description\":\"Subsurface mining is a process that involves the extraction of a metal or fossil fuel from the ground. It is the most well-known mining method.\",\"breadcrumb\":{\"@id\":\"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/metalpie.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\/\/metalpie.com\/blog\/category\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Subsurface mining methods\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/metalpie.com\/#website\",\"url\":\"https:\/\/metalpie.com\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/metalpie.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71\",\"name\":\"DC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/metalpie.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1778646337\",\"contentUrl\":\"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1778646337\",\"caption\":\"DC\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9thodes d'exploitation souterraine","description":"L'exploitation mini\u00e8re souterraine est un processus qui implique l'extraction d'un m\u00e9tal ou d'un combustible fossile du sol. C'est la m\u00e9thode d'exploitation mini\u00e8re la plus connue.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/fr\/blog\/methodes-dexploitation-souterraine\/","og_locale":"fr_FR","og_type":"article","og_title":"Subsurface Mining Methods","og_description":"Subsurface mining is a process that involves the extraction of a metal or fossil fuel from the ground. It is the most well-known mining method.","og_url":"https:\/\/metalpie.com\/fr\/blog\/methodes-dexploitation-souterraine\/","og_site_name":"METALPIE","article_published_time":"2021-10-08T07:30:27+00:00","article_modified_time":"2025-10-06T16:18:53+00:00","og_image":[{"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2021\/10\/subsurface-mining-machinery.webp"}],"author":"DC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"DC","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/","url":"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/","name":"M\u00e9thodes d'exploitation souterraine","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"datePublished":"2021-10-08T07:30:27+00:00","dateModified":"2025-10-06T16:18:53+00:00","author":{"@id":"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71"},"description":"L'exploitation mini\u00e8re souterraine est un processus qui implique l'extraction d'un m\u00e9tal ou d'un combustible fossile du sol. C'est la m\u00e9thode d'exploitation mini\u00e8re la plus connue.","breadcrumb":{"@id":"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/blog\/subsurface-mining-methods\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/metalpie.com\/blog\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"Subsurface mining methods"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabrication de pr\u00e9cision des m\u00e9taux | Outils, processus et autres","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/metalpie.com\/#\/schema\/person\/d344990177b678113288be4309906d71","name":"DC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/metalpie.com\/#\/schema\/person\/image\/","url":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1778646337","contentUrl":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/8c71088722c91e6dc508a2d3a792c20e.jpg?ver=1778646337","caption":"DC"}}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts\/14735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/comments?post=14735"}],"version-history":[{"count":0,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/posts\/14735\/revisions"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/media?parent=14735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/categories?post=14735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metalpie.com\/fr\/wp-json\/wp\/v2\/tags?post=14735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}