{"id":3461,"date":"2023-03-03T11:48:50","date_gmt":"2023-03-03T03:48:50","guid":{"rendered":"https:\/\/metalpie.com\/?p=3461"},"modified":"2023-03-03T11:51:13","modified_gmt":"2023-03-03T03:51:13","slug":"huajians-nueva-maquina-extrusora-de-10000-toneladas","status":"publish","type":"post","link":"https:\/\/metalpie.com\/es\/blog\/huajians-nueva-maquina-extrusora-de-10000-toneladas\/","title":{"rendered":"Nueva m\u00e1quina extrusora de 10.000 toneladas de HUAJIAN"},"content":{"rendered":"<p>La nueva m\u00e1quina extrusora de 10.000 toneladas de HUAJIAN comenz\u00f3 la producci\u00f3n de prueba en la ma\u00f1ana del 28 de febrero en la f\u00e1brica HUAJIAN NO.3 despu\u00e9s de una larga instalaci\u00f3n y depuraci\u00f3n. Nuestros departamentos de producci\u00f3n, gesti\u00f3n, din\u00e1mica de equipos y calidad t\u00e9cnica est\u00e1n presentes y a la espera de resolver los posibles problemas t\u00e9cnicos. A continuaci\u00f3n, el perfil de aluminio industrial de gran tama\u00f1o fue extruido de la nueva m\u00e1quina de extrusi\u00f3n, lo que demuestra el \u00e9xito de la producci\u00f3n de prueba y la innovaci\u00f3n.<\/p>\n\t<section class=\"section\" id=\"section_914329465\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1285977031\">\n\n\t<div id=\"col-695121922\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2099100383\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruder_machine.webp\" class=\"attachment-large size-large\" alt=\"m\u00e1quina extrusora\" srcset=\"https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruder_machine.webp 1000w, https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruder_machine-300x225.webp 300w, https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruder_machine-768x576.webp 768w, https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruder_machine-800x600.webp 800w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2099100383 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1874871566\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_914329465 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_2019279602\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-654660782\">\n\n\t<div id=\"col-1625804538\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>La m\u00e1quina extrusora de 1000 toneladas es importante para la industria manufacturera moderna. Su producci\u00f3n de prueba sin problemas mejorar\u00e1 nuestra capacidad de fabricaci\u00f3n de perfiles de aluminio. Esta m\u00e1quina de extrusi\u00f3n ayudar\u00e1 a la transici\u00f3n de la industria del aluminio y al desarrollo de alta calidad del condado de Linqu, 'la Ciudad del Aluminio'.<br \/>\nA continuaci\u00f3n, seguiremos siempre el ritmo de la tecnolog\u00eda y contribuiremos al desarrollo de la industria del aluminio.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2019279602 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"<p>La nueva m\u00e1quina extrusora de 10.000 toneladas de HUAJIAN comenz\u00f3 la producci\u00f3n de prueba en la ma\u00f1ana del 28 de febrero en la f\u00e1brica HUAJIAN NO.3 despu\u00e9s de una larga instalaci\u00f3n y depuraci\u00f3n. Nuestros departamentos de producci\u00f3n, gesti\u00f3n, din\u00e1mica de equipos y calidad t\u00e9cnica est\u00e1n presentes y a la espera de resolver los posibles problemas t\u00e9cnicos. A continuaci\u00f3n, el perfil de aluminio industrial de gran tama\u00f1o se...<\/p>","protected":false},"author":15,"featured_media":3464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>HUAJIAN&#039;S New 10,000-ton Extruding Machine<\/title>\n<meta name=\"description\" content=\"The new 10,000-ton extruding machine is developed by HUAJIAN company. Its successful trial production will improve our manufacturing capacity in aluminum profiles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metalpie.com\/es\/blog\/huajians-nueva-maquina-extrusora-de-10000-toneladas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HUAJIAN&#039;S New 10,000-ton Extruding Machine\" \/>\n<meta property=\"og:description\" content=\"The new 10,000-ton extruding machine is developed by HUAJIAN company. Its successful trial production will improve our manufacturing capacity in aluminum profiles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metalpie.com\/es\/blog\/huajians-nueva-maquina-extrusora-de-10000-toneladas\/\" \/>\n<meta property=\"og:site_name\" content=\"METALPIE\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T03:48:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T03:51:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruding_machine.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"DALU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DALU\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/\",\"url\":\"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/\",\"name\":\"HUAJIAN'S New 10,000-ton Extruding Machine\",\"isPartOf\":{\"@id\":\"https:\/\/metalpie.com\/#website\"},\"datePublished\":\"2023-03-03T03:48:50+00:00\",\"dateModified\":\"2023-03-03T03:51:13+00:00\",\"author\":{\"@id\":\"https:\/\/metalpie.com\/#\/schema\/person\/a56005e8eedae5974accba511085eb3d\"},\"description\":\"The new 10,000-ton extruding machine is developed by HUAJIAN company. Its successful trial production will improve our manufacturing capacity in aluminum profiles.\",\"breadcrumb\":{\"@id\":\"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/metalpie.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\/\/metalpie.com\/blog\/category\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HUAJIAN&#8217;S New 10,000-ton Extruding Machine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/metalpie.com\/#website\",\"url\":\"https:\/\/metalpie.com\/\",\"name\":\"METALPIE\",\"description\":\"Precision Metal Fabrication | Tools, Processes &amp; More\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/metalpie.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/metalpie.com\/#\/schema\/person\/a56005e8eedae5974accba511085eb3d\",\"name\":\"DALU\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/metalpie.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/49e526758b048fed7355a5d635da10c0.jpg?ver=1778645280\",\"contentUrl\":\"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/49e526758b048fed7355a5d635da10c0.jpg?ver=1778645280\",\"caption\":\"DALU\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva m\u00e1quina extrusora de 10.000 toneladas de HUAJIAN","description":"La nueva m\u00e1quina extrusora de 10.000 toneladas ha sido desarrollada por la empresa HUAJIAN. Su exitosa producci\u00f3n de prueba mejorar\u00e1 nuestra capacidad de fabricaci\u00f3n de perfiles de aluminio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metalpie.com\/es\/blog\/huajians-nueva-maquina-extrusora-de-10000-toneladas\/","og_locale":"es_ES","og_type":"article","og_title":"HUAJIAN'S New 10,000-ton Extruding Machine","og_description":"The new 10,000-ton extruding machine is developed by HUAJIAN company. Its successful trial production will improve our manufacturing capacity in aluminum profiles.","og_url":"https:\/\/metalpie.com\/es\/blog\/huajians-nueva-maquina-extrusora-de-10000-toneladas\/","og_site_name":"METALPIE","article_published_time":"2023-03-03T03:48:50+00:00","article_modified_time":"2023-03-03T03:51:13+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/metalpie.com\/wp-content\/uploads\/2023\/03\/extruding_machine.webp","type":"image\/webp"}],"author":"DALU","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"DALU","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/","url":"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/","name":"Nueva m\u00e1quina extrusora de 10.000 toneladas de HUAJIAN","isPartOf":{"@id":"https:\/\/metalpie.com\/#website"},"datePublished":"2023-03-03T03:48:50+00:00","dateModified":"2023-03-03T03:51:13+00:00","author":{"@id":"https:\/\/metalpie.com\/#\/schema\/person\/a56005e8eedae5974accba511085eb3d"},"description":"La nueva m\u00e1quina extrusora de 10.000 toneladas ha sido desarrollada por la empresa HUAJIAN. Su exitosa producci\u00f3n de prueba mejorar\u00e1 nuestra capacidad de fabricaci\u00f3n de perfiles de aluminio.","breadcrumb":{"@id":"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/metalpie.com\/blog\/huajians-new-10000-ton-extruding-machine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metalpie.com\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/metalpie.com\/blog\/category\/blog\/"},{"@type":"ListItem","position":3,"name":"HUAJIAN&#8217;S New 10,000-ton Extruding Machine"}]},{"@type":"WebSite","@id":"https:\/\/metalpie.com\/#website","url":"https:\/\/metalpie.com\/","name":"METALPIE","description":"Fabricaci\u00f3n de metales de precisi\u00f3n | Herramientas, procesos y m\u00e1s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metalpie.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/metalpie.com\/#\/schema\/person\/a56005e8eedae5974accba511085eb3d","name":"DALU","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/metalpie.com\/#\/schema\/person\/image\/","url":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/49e526758b048fed7355a5d635da10c0.jpg?ver=1778645280","contentUrl":"https:\/\/metalpie.com\/wp-content\/litespeed\/avatar\/49e526758b048fed7355a5d635da10c0.jpg?ver=1778645280","caption":"DALU"}}]}},"_links":{"self":[{"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/posts\/3461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/comments?post=3461"}],"version-history":[{"count":0,"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/posts\/3461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/media\/3464"}],"wp:attachment":[{"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/media?parent=3461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/categories?post=3461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metalpie.com\/es\/wp-json\/wp\/v2\/tags?post=3461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}